{"id":12084,"date":"2026-02-19T11:20:24","date_gmt":"2026-02-19T11:20:24","guid":{"rendered":"https:\/\/www.masseriabambarone.com\/things-to-do\/"},"modified":"2026-08-18T12:05:32","modified_gmt":"2026-08-18T12:05:32","slug":"things-to-do","status":"publish","type":"page","link":"https:\/\/www.masseriabambarone.com\/de\/things-to-do\/","title":{"rendered":"Things to do"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11779,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/pages\/12084"}],"collection":[{"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/comments?post=12084"}],"version-history":[{"count":8,"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/pages\/12084\/revisions"}],"predecessor-version":[{"id":13456,"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/pages\/12084\/revisions\/13456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/media\/11779"}],"wp:attachment":[{"href":"https:\/\/www.masseriabambarone.com\/de\/wp-json\/wp\/v2\/media?parent=12084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}