{"id":12050,"date":"2023-04-06T09:53:05","date_gmt":"2023-04-06T09:53:05","guid":{"rendered":"https:\/\/www.masseriabambarone.com\/events\/"},"modified":"2026-05-18T15:27:52","modified_gmt":"2026-05-18T15:27:52","slug":"events","status":"publish","type":"page","link":"https:\/\/www.masseriabambarone.com\/it\/events\/","title":{"rendered":"Events"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11599,"parent":0,"menu_order":56,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/pages\/12050"}],"collection":[{"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/comments?post=12050"}],"version-history":[{"count":11,"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/pages\/12050\/revisions"}],"predecessor-version":[{"id":12953,"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/pages\/12050\/revisions\/12953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/media\/11599"}],"wp:attachment":[{"href":"https:\/\/www.masseriabambarone.com\/it\/wp-json\/wp\/v2\/media?parent=12050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}